{"id":783,"date":"2022-01-23T15:20:16","date_gmt":"2022-01-23T12:20:16","guid":{"rendered":"https:\/\/signaturebmx.com\/?post_type=product&#038;p=783"},"modified":"2026-06-05T12:09:29","modified_gmt":"2026-06-05T10:09:29","slug":"odyssey-monolever-small","status":"publish","type":"product","link":"https:\/\/signaturebmx.com\/en\/tuote\/odyssey-monolever-small\/","title":{"rendered":"Odyssey Monolever Small"},"content":{"rendered":"<p>Lyhyt jarrukahva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lyhyt jarrukahva.<\/p>\n","protected":false},"featured_media":4572,"template":"","meta":[],"product_brand":[],"product_cat":[55],"product_tag":[42],"class_list":["post-783","product","type-product","status-publish","has-post-thumbnail","product_cat-jarrukahvat","product_tag-odyssey","pa_tuotemerkki-odyssey","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Odyssey Monolever Small | Signature Bmx | Bmx-kauppa<\/title>\n<meta name=\"description\" content=\"Laadukkaat bmx-py\u00f6r\u00e4t, osat ja tarvikkeet nopealla toimituksella suomalaisesta bmx-kaupasta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/signaturebmx.com\/en\/tuote\/odyssey-monolever-small\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Odyssey Monolever Small | Signature Bmx | Bmx-kauppa\" \/>\n<meta property=\"og:description\" content=\"Laadukkaat bmx-py\u00f6r\u00e4t, osat ja tarvikkeet nopealla toimituksella suomalaisesta bmx-kaupasta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/signaturebmx.com\/en\/tuote\/odyssey-monolever-small\/\" \/>\n<meta property=\"og:site_name\" content=\"Signature Bmx\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SignatureBMX\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-05T10:09:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/signaturebmx.com\/wp-content\/uploads\/2023\/10\/odyssey_monolever_small.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/tuote\\\/odyssey-monolever-small\\\/\",\"url\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/tuote\\\/odyssey-monolever-small\\\/\",\"name\":\"Odyssey Monolever Small | Signature Bmx | Bmx-kauppa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/tuote\\\/odyssey-monolever-small\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/tuote\\\/odyssey-monolever-small\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/signaturebmx.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/odyssey_monolever_small.jpg\",\"datePublished\":\"2022-01-23T12:20:16+00:00\",\"dateModified\":\"2026-06-05T10:09:29+00:00\",\"description\":\"Laadukkaat bmx-py\u00f6r\u00e4t, osat ja tarvikkeet nopealla toimituksella suomalaisesta bmx-kaupasta.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/tuote\\\/odyssey-monolever-small\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/signaturebmx.com\\\/en\\\/tuote\\\/odyssey-monolever-small\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/tuote\\\/odyssey-monolever-small\\\/#primaryimage\",\"url\":\"https:\\\/\\\/signaturebmx.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/odyssey_monolever_small.jpg\",\"contentUrl\":\"https:\\\/\\\/signaturebmx.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/odyssey_monolever_small.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/tuote\\\/odyssey-monolever-small\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/shop-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Odyssey Monolever Small\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/\",\"name\":\"Signature Bmx\",\"description\":\"Bmx-kauppa\",\"publisher\":{\"@id\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/#organization\"},\"alternateName\":\"Signature Bmx\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/#organization\",\"name\":\"Signature Bmx\",\"alternateName\":\"Signature Bmx\",\"url\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/signaturebmx.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/cropped-favicon_si.png\",\"contentUrl\":\"https:\\\/\\\/signaturebmx.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/cropped-favicon_si.png\",\"width\":512,\"height\":512,\"caption\":\"Signature Bmx\"},\"image\":{\"@id\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SignatureBMX\",\"https:\\\/\\\/www.instagram.com\\\/signaturebmx\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Odyssey Monolever Small | Signature Bmx | Bmx-kauppa","description":"Laadukkaat bmx-py\u00f6r\u00e4t, osat ja tarvikkeet nopealla toimituksella suomalaisesta bmx-kaupasta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/signaturebmx.com\/en\/tuote\/odyssey-monolever-small\/","og_locale":"en_US","og_type":"article","og_title":"Odyssey Monolever Small | Signature Bmx | Bmx-kauppa","og_description":"Laadukkaat bmx-py\u00f6r\u00e4t, osat ja tarvikkeet nopealla toimituksella suomalaisesta bmx-kaupasta.","og_url":"https:\/\/signaturebmx.com\/en\/tuote\/odyssey-monolever-small\/","og_site_name":"Signature Bmx","article_publisher":"https:\/\/www.facebook.com\/SignatureBMX","article_modified_time":"2026-06-05T10:09:29+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/signaturebmx.com\/wp-content\/uploads\/2023\/10\/odyssey_monolever_small.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/signaturebmx.com\/en\/tuote\/odyssey-monolever-small\/","url":"https:\/\/signaturebmx.com\/en\/tuote\/odyssey-monolever-small\/","name":"Odyssey Monolever Small | Signature Bmx | Bmx-kauppa","isPartOf":{"@id":"https:\/\/signaturebmx.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/signaturebmx.com\/en\/tuote\/odyssey-monolever-small\/#primaryimage"},"image":{"@id":"https:\/\/signaturebmx.com\/en\/tuote\/odyssey-monolever-small\/#primaryimage"},"thumbnailUrl":"https:\/\/signaturebmx.com\/wp-content\/uploads\/2023\/10\/odyssey_monolever_small.jpg","datePublished":"2022-01-23T12:20:16+00:00","dateModified":"2026-06-05T10:09:29+00:00","description":"Laadukkaat bmx-py\u00f6r\u00e4t, osat ja tarvikkeet nopealla toimituksella suomalaisesta bmx-kaupasta.","breadcrumb":{"@id":"https:\/\/signaturebmx.com\/en\/tuote\/odyssey-monolever-small\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/signaturebmx.com\/en\/tuote\/odyssey-monolever-small\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/signaturebmx.com\/en\/tuote\/odyssey-monolever-small\/#primaryimage","url":"https:\/\/signaturebmx.com\/wp-content\/uploads\/2023\/10\/odyssey_monolever_small.jpg","contentUrl":"https:\/\/signaturebmx.com\/wp-content\/uploads\/2023\/10\/odyssey_monolever_small.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/signaturebmx.com\/en\/tuote\/odyssey-monolever-small\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/signaturebmx.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/signaturebmx.com\/en\/shop-2\/"},{"@type":"ListItem","position":3,"name":"Odyssey Monolever Small"}]},{"@type":"WebSite","@id":"https:\/\/signaturebmx.com\/en\/#website","url":"https:\/\/signaturebmx.com\/en\/","name":"Signature Bmx","description":"Bmx-kauppa","publisher":{"@id":"https:\/\/signaturebmx.com\/en\/#organization"},"alternateName":"Signature Bmx","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/signaturebmx.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/signaturebmx.com\/en\/#organization","name":"Signature Bmx","alternateName":"Signature Bmx","url":"https:\/\/signaturebmx.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/signaturebmx.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/signaturebmx.com\/wp-content\/uploads\/2022\/02\/cropped-favicon_si.png","contentUrl":"https:\/\/signaturebmx.com\/wp-content\/uploads\/2022\/02\/cropped-favicon_si.png","width":512,"height":512,"caption":"Signature Bmx"},"image":{"@id":"https:\/\/signaturebmx.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SignatureBMX","https:\/\/www.instagram.com\/signaturebmx\/"]}]}},"_links":{"self":[{"href":"https:\/\/signaturebmx.com\/en\/wp-json\/wp\/v2\/product\/783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/signaturebmx.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/signaturebmx.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/signaturebmx.com\/en\/wp-json\/wp\/v2\/media\/4572"}],"wp:attachment":[{"href":"https:\/\/signaturebmx.com\/en\/wp-json\/wp\/v2\/media?parent=783"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/signaturebmx.com\/en\/wp-json\/wp\/v2\/product_brand?post=783"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/signaturebmx.com\/en\/wp-json\/wp\/v2\/product_cat?post=783"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/signaturebmx.com\/en\/wp-json\/wp\/v2\/product_tag?post=783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}