{"id":1109,"date":"2022-01-23T15:23:59","date_gmt":"2022-01-23T12:23:59","guid":{"rendered":"https:\/\/signaturebmx.com\/?post_type=product&#038;p=1109"},"modified":"2026-05-22T08:29:00","modified_gmt":"2026-05-22T06:29:00","slug":"odyssey-travel-tool","status":"publish","type":"product","link":"https:\/\/signaturebmx.com\/en\/tuote\/odyssey-travel-tool\/","title":{"rendered":"Odyssey Travel Tool"},"content":{"rendered":"<p>Monik\u00e4ytt\u00f6inen ty\u00f6kalu.<br \/>\n-4mm, 5mm, 6mm, and 8mm kuusiokolot<br \/>\n-17mm pitk\u00e4 hylsyavain<br \/>\n-15mm ja 17mm poljinavaimet<br \/>\n______<\/p>\n<p>Our first multi-tool includes all the key bits to assemble and disassemble your bike on-the-go. Includes a pedal wrench, 4, 5, 6 and 8mm hex wrenches and a 17mm socket with an integrated storage compartment. It&#8217;s light and easy to carry, but big enough to allow you to actually tighten everything down properly.<\/p>\n<p>Features<br \/>\n4mm, 5mm, 6mm, and 8mm hex wrenches<br \/>\n17mm deep socket<br \/>\nIntegrated storage compartment<br \/>\nPedal Wrench (15mm and 17mm spanners included)<br \/>\nFull length arm for proper leverage<br \/>\nMost affordable compact BMX multi-tool<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Monik\u00e4ytt\u00f6inen ty\u00f6kalu. -4mm, 5mm, 6mm, and 8mm kuusiokolot -17mm pitk\u00e4 hylsyavain -15mm ja 17mm poljinavaimet ______ Our first multi-tool includes all the key bits to assemble and disassemble your bike on-the-go. Includes a pedal wrench, 4, 5, 6 and 8mm hex wrenches and a 17mm socket with an integrated storage compartment. It&#8217;s light and easy [&#8230;]\n","protected":false},"featured_media":573,"template":"","meta":[],"product_brand":[],"product_cat":[116],"product_tag":[42],"class_list":["post-1109","product","type-product","status-publish","has-post-thumbnail","product_cat-tyokalut","product_tag-odyssey","pa_tuotemerkki-odyssey","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Odyssey Travel Tool | Signature Bmx | Bmx-kauppa<\/title>\n<meta name=\"description\" content=\"Laadukkaat bmx-py\u00f6r\u00e4t, osat ja tarvikkeet nopealla toimituksella suomalaisesta bmx-kaupasta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/signaturebmx.com\/en\/tuote\/odyssey-travel-tool\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Odyssey Travel Tool | Signature Bmx | Bmx-kauppa\" \/>\n<meta property=\"og:description\" content=\"Laadukkaat bmx-py\u00f6r\u00e4t, osat ja tarvikkeet nopealla toimituksella suomalaisesta bmx-kaupasta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/signaturebmx.com\/en\/tuote\/odyssey-travel-tool\/\" \/>\n<meta property=\"og:site_name\" content=\"Signature Bmx\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SignatureBMX\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-22T06:29:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/signaturebmx.com\/wp-content\/uploads\/2022\/01\/odyssey_travel_tool_2102_4c7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/tuote\\\/odyssey-travel-tool\\\/\",\"url\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/tuote\\\/odyssey-travel-tool\\\/\",\"name\":\"Odyssey Travel Tool | Signature Bmx | Bmx-kauppa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/tuote\\\/odyssey-travel-tool\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/tuote\\\/odyssey-travel-tool\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/signaturebmx.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/odyssey_travel_tool_2102_4c7.jpg\",\"datePublished\":\"2022-01-23T12:23:59+00:00\",\"dateModified\":\"2026-05-22T06:29:00+00:00\",\"description\":\"Laadukkaat bmx-py\u00f6r\u00e4t, osat ja tarvikkeet nopealla toimituksella suomalaisesta bmx-kaupasta.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/tuote\\\/odyssey-travel-tool\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/signaturebmx.com\\\/en\\\/tuote\\\/odyssey-travel-tool\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/tuote\\\/odyssey-travel-tool\\\/#primaryimage\",\"url\":\"https:\\\/\\\/signaturebmx.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/odyssey_travel_tool_2102_4c7.jpg\",\"contentUrl\":\"https:\\\/\\\/signaturebmx.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/odyssey_travel_tool_2102_4c7.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/tuote\\\/odyssey-travel-tool\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/shop-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Odyssey Travel Tool\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/\",\"name\":\"Signature Bmx\",\"description\":\"Bmx-kauppa\",\"publisher\":{\"@id\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/#organization\"},\"alternateName\":\"Signature Bmx\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/#organization\",\"name\":\"Signature Bmx\",\"alternateName\":\"Signature Bmx\",\"url\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/signaturebmx.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/cropped-favicon_si.png\",\"contentUrl\":\"https:\\\/\\\/signaturebmx.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/cropped-favicon_si.png\",\"width\":512,\"height\":512,\"caption\":\"Signature Bmx\"},\"image\":{\"@id\":\"https:\\\/\\\/signaturebmx.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SignatureBMX\",\"https:\\\/\\\/www.instagram.com\\\/signaturebmx\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Odyssey Travel Tool | Signature Bmx | Bmx-kauppa","description":"Laadukkaat bmx-py\u00f6r\u00e4t, osat ja tarvikkeet nopealla toimituksella suomalaisesta bmx-kaupasta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/signaturebmx.com\/en\/tuote\/odyssey-travel-tool\/","og_locale":"en_US","og_type":"article","og_title":"Odyssey Travel Tool | Signature Bmx | Bmx-kauppa","og_description":"Laadukkaat bmx-py\u00f6r\u00e4t, osat ja tarvikkeet nopealla toimituksella suomalaisesta bmx-kaupasta.","og_url":"https:\/\/signaturebmx.com\/en\/tuote\/odyssey-travel-tool\/","og_site_name":"Signature Bmx","article_publisher":"https:\/\/www.facebook.com\/SignatureBMX","article_modified_time":"2026-05-22T06:29:00+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/signaturebmx.com\/wp-content\/uploads\/2022\/01\/odyssey_travel_tool_2102_4c7.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/signaturebmx.com\/en\/tuote\/odyssey-travel-tool\/","url":"https:\/\/signaturebmx.com\/en\/tuote\/odyssey-travel-tool\/","name":"Odyssey Travel Tool | Signature Bmx | Bmx-kauppa","isPartOf":{"@id":"https:\/\/signaturebmx.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/signaturebmx.com\/en\/tuote\/odyssey-travel-tool\/#primaryimage"},"image":{"@id":"https:\/\/signaturebmx.com\/en\/tuote\/odyssey-travel-tool\/#primaryimage"},"thumbnailUrl":"https:\/\/signaturebmx.com\/wp-content\/uploads\/2022\/01\/odyssey_travel_tool_2102_4c7.jpg","datePublished":"2022-01-23T12:23:59+00:00","dateModified":"2026-05-22T06:29:00+00:00","description":"Laadukkaat bmx-py\u00f6r\u00e4t, osat ja tarvikkeet nopealla toimituksella suomalaisesta bmx-kaupasta.","breadcrumb":{"@id":"https:\/\/signaturebmx.com\/en\/tuote\/odyssey-travel-tool\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/signaturebmx.com\/en\/tuote\/odyssey-travel-tool\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/signaturebmx.com\/en\/tuote\/odyssey-travel-tool\/#primaryimage","url":"https:\/\/signaturebmx.com\/wp-content\/uploads\/2022\/01\/odyssey_travel_tool_2102_4c7.jpg","contentUrl":"https:\/\/signaturebmx.com\/wp-content\/uploads\/2022\/01\/odyssey_travel_tool_2102_4c7.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/signaturebmx.com\/en\/tuote\/odyssey-travel-tool\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/signaturebmx.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/signaturebmx.com\/en\/shop-2\/"},{"@type":"ListItem","position":3,"name":"Odyssey Travel Tool"}]},{"@type":"WebSite","@id":"https:\/\/signaturebmx.com\/en\/#website","url":"https:\/\/signaturebmx.com\/en\/","name":"Signature Bmx","description":"Bmx-kauppa","publisher":{"@id":"https:\/\/signaturebmx.com\/en\/#organization"},"alternateName":"Signature Bmx","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/signaturebmx.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/signaturebmx.com\/en\/#organization","name":"Signature Bmx","alternateName":"Signature Bmx","url":"https:\/\/signaturebmx.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/signaturebmx.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/signaturebmx.com\/wp-content\/uploads\/2022\/02\/cropped-favicon_si.png","contentUrl":"https:\/\/signaturebmx.com\/wp-content\/uploads\/2022\/02\/cropped-favicon_si.png","width":512,"height":512,"caption":"Signature Bmx"},"image":{"@id":"https:\/\/signaturebmx.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SignatureBMX","https:\/\/www.instagram.com\/signaturebmx\/"]}]}},"_links":{"self":[{"href":"https:\/\/signaturebmx.com\/en\/wp-json\/wp\/v2\/product\/1109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/signaturebmx.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/signaturebmx.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/signaturebmx.com\/en\/wp-json\/wp\/v2\/media\/573"}],"wp:attachment":[{"href":"https:\/\/signaturebmx.com\/en\/wp-json\/wp\/v2\/media?parent=1109"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/signaturebmx.com\/en\/wp-json\/wp\/v2\/product_brand?post=1109"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/signaturebmx.com\/en\/wp-json\/wp\/v2\/product_cat?post=1109"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/signaturebmx.com\/en\/wp-json\/wp\/v2\/product_tag?post=1109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}